{"id":1188,"count":7,"description":"","link":"https:\/\/nimedixmedical.com\/fr\/categorie-produit\/balances-et-compteurs\/balances-medicales-pour-adultes\/balances-plate-forme\/","name":"Balances plate-forme","slug":"balances-plate-forme","taxonomy":"product_cat","parent":1185,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/nimedixmedical.com\/fr\/wp-json\/wp\/v2\/product_cat\/1188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimedixmedical.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/nimedixmedical.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/nimedixmedical.com\/fr\/wp-json\/wp\/v2\/product_cat\/1185"}],"wp:post_type":[{"href":"https:\/\/nimedixmedical.com\/fr\/wp-json\/wp\/v2\/product?product_cat=1188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}