{"id":1195,"count":28,"description":"","link":"https:\/\/nimedixmedical.com\/en\/product-category\/medical-cases\/sacs-et-sacs-a-dos-en-nylon\/","name":"Bags and backpacks nylon","slug":"sacs-et-sacs-a-dos-en-nylon","taxonomy":"product_cat","parent":1194,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/nimedixmedical.com\/en\/wp-json\/wp\/v2\/product_cat\/1195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimedixmedical.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/nimedixmedical.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/nimedixmedical.com\/en\/wp-json\/wp\/v2\/product_cat\/1194"}],"wp:post_type":[{"href":"https:\/\/nimedixmedical.com\/en\/wp-json\/wp\/v2\/product?product_cat=1195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}